{"id":12385,"date":"2017-03-08T14:03:18","date_gmt":"2017-03-08T12:03:18","guid":{"rendered":"http:\/\/www.verdi.bz.it\/?p=12385"},"modified":"2021-07-06T08:37:58","modified_gmt":"2021-07-06T06:37:58","slug":"impegno-per-i-diritti-delle-donne-attuale-come-sempre","status":"publish","type":"post","link":"https:\/\/www.verdi.bz.it\/it\/impegno-per-i-diritti-delle-donne-attuale-come-sempre\/","title":{"rendered":"Impegno per i diritti delle donne &#8211; attuale come sempre"},"content":{"rendered":"<p>Grazie alle nostre predecessore, a tutte le donne che hanno lottato per i loro diritti, a tutte le femministe, pacifiste, artiste e scienziate, nonne, madri, amiche che ci hanno dato il coraggio di vivere e essere protagoniste della nostra vita. Grazie a tutte loro che hanno conquistato i diritti per tutte noi. Diritti che oggi ci sembrano cos\u00ec ovvi. Grazie per aver sopportato ogni tipo di insulto per aver richiesto un posto alla pari nella nostra societ\u00e0<br \/>\nL&#8217;ovviet\u00e0 di tali diritti \u00e8 fragile. Le quote rosa vengono continuamente messe in discussione e considerate non indispensabili. Eppure in Italia solo il 20% delle donne sono rappresentate in politica e nelle posizioni dirigenziali del mondo economico. Nelle banche sono solo il 10%. Il ruolo tradizionale della famiglia viene difeso a spada tratta, mentre la maggior parte degli atti di violenza contro le donne avviene proprio dietro le mura di casa.<br \/>\nPensiamo che le donne abbiano bisogno soprattutto di una cosa: il sostegno di una societ\u00e0, di uomini e donne che vedano in loro il potenziale e non la vittima. E non hanno invece bisogno di una societ\u00e0 che le metta &#8220;sotto tutela&#8221;, prescrivendo loro come debbano vestirsi e a quale ruolo si debbano limitare.<br \/>\nC&#8217;\u00e8 ancora molta strada da fare. Ogni donna gode di diritti inalienabili per cui per\u00f2 deve lottare ogni giorno. E noi lottiamo insieme.<\/p>\n<p>Ulrike Spitaler<br \/>\nEvelyn Gruber Fischnaller<br \/>\nDonne Verdi &#8211; Gr\u00fcne Frauen<\/p>\n<p>08\/03\/2017<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grazie alle nostre predecessore, a tutte le donne che hanno lottato per i loro diritti, a tutte le femministe, pacifiste, artiste e scienziate, nonne, madri, amiche che ci hanno dato il coraggio di vivere e essere protagoniste della nostra vita. Grazie a tutte loro che [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17156,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1071,873,672],"tags":[],"_links":{"self":[{"href":"https:\/\/www.verdi.bz.it\/it\/wp-json\/wp\/v2\/posts\/12385"}],"collection":[{"href":"https:\/\/www.verdi.bz.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.verdi.bz.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.verdi.bz.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.verdi.bz.it\/it\/wp-json\/wp\/v2\/comments?post=12385"}],"version-history":[{"count":2,"href":"https:\/\/www.verdi.bz.it\/it\/wp-json\/wp\/v2\/posts\/12385\/revisions"}],"predecessor-version":[{"id":17158,"href":"https:\/\/www.verdi.bz.it\/it\/wp-json\/wp\/v2\/posts\/12385\/revisions\/17158"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.verdi.bz.it\/it\/wp-json\/wp\/v2\/media\/17156"}],"wp:attachment":[{"href":"https:\/\/www.verdi.bz.it\/it\/wp-json\/wp\/v2\/media?parent=12385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.verdi.bz.it\/it\/wp-json\/wp\/v2\/categories?post=12385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.verdi.bz.it\/it\/wp-json\/wp\/v2\/tags?post=12385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}